{"id":33,"count":24,"description":"","link":"https:\/\/www.ovwg.at\/en\/category\/event-en\/","name":"Event","slug":"event-en","taxonomy":"category","parent":0,"meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Event Archive - OVWG - \u00d6sterreichische Vereinigung f\u00fcr Wetten &amp; Gl\u00fccksspiel<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ovwg.at\/en\/category\/event-en\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Event Archive - OVWG - \u00d6sterreichische Vereinigung f\u00fcr Wetten &amp; Gl\u00fccksspiel\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ovwg.at\/en\/category\/event-en\/\" \/>\n<meta property=\"og:site_name\" content=\"OVWG - \u00d6sterreichische Vereinigung f\u00fcr Wetten &amp; Gl\u00fccksspiel\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.ovwg.at\\\/en\\\/category\\\/event-en\\\/\",\"url\":\"https:\\\/\\\/www.ovwg.at\\\/en\\\/category\\\/event-en\\\/\",\"name\":\"Event Archive - OVWG - \u00d6sterreichische Vereinigung f\u00fcr Wetten &amp; Gl\u00fccksspiel\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ovwg.at\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.ovwg.at\\\/en\\\/category\\\/event-en\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.ovwg.at\\\/en\\\/category\\\/event-en\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.ovwg.at\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Event\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.ovwg.at\\\/#website\",\"url\":\"https:\\\/\\\/www.ovwg.at\\\/\",\"name\":\"OVWG - \u00d6sterreichische Vereinigung f\u00fcr Wetten &amp; Gl\u00fccksspiel\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.ovwg.at\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Event Archive - OVWG - \u00d6sterreichische Vereinigung f\u00fcr Wetten &amp; Gl\u00fccksspiel","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ovwg.at\/en\/category\/event-en\/","og_locale":"en_US","og_type":"article","og_title":"Event Archive - OVWG - \u00d6sterreichische Vereinigung f\u00fcr Wetten &amp; Gl\u00fccksspiel","og_url":"https:\/\/www.ovwg.at\/en\/category\/event-en\/","og_site_name":"OVWG - \u00d6sterreichische Vereinigung f\u00fcr Wetten &amp; Gl\u00fccksspiel","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.ovwg.at\/en\/category\/event-en\/","url":"https:\/\/www.ovwg.at\/en\/category\/event-en\/","name":"Event Archive - OVWG - \u00d6sterreichische Vereinigung f\u00fcr Wetten &amp; Gl\u00fccksspiel","isPartOf":{"@id":"https:\/\/www.ovwg.at\/#website"},"breadcrumb":{"@id":"https:\/\/www.ovwg.at\/en\/category\/event-en\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/www.ovwg.at\/en\/category\/event-en\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.ovwg.at\/en\/"},{"@type":"ListItem","position":2,"name":"Event"}]},{"@type":"WebSite","@id":"https:\/\/www.ovwg.at\/#website","url":"https:\/\/www.ovwg.at\/","name":"OVWG - \u00d6sterreichische Vereinigung f\u00fcr Wetten &amp; Gl\u00fccksspiel","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ovwg.at\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/www.ovwg.at\/en\/wp-json\/wp\/v2\/categories\/33","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ovwg.at\/en\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/www.ovwg.at\/en\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/www.ovwg.at\/en\/wp-json\/wp\/v2\/posts?categories=33"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}